{"id":111,"count":281,"description":"","link":"https:\/\/dypall.com\/es\/category\/activity\/","name":"Activity","slug":"activity","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Activity Archives - DYPALL Network<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dypall.com\/es\/category\/activity\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Activity Archives - DYPALL Network\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dypall.com\/es\/category\/activity\/\" \/>\n<meta property=\"og:site_name\" content=\"DYPALL Network\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/dypall.com\/category\/activity\/\",\"url\":\"https:\/\/dypall.com\/category\/activity\/\",\"name\":\"Activity Archives - DYPALL Network\",\"isPartOf\":{\"@id\":\"https:\/\/dypall.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/dypall.com\/category\/activity\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dypall.com\/category\/activity\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dypall.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Activity\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dypall.com\/#website\",\"url\":\"https:\/\/dypall.com\/\",\"name\":\"DYPALL Network\",\"description\":\"We are a European network of civil society organisations, municipalities and research institutions dedicated to improving democracy through youth participation.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dypall.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Activity Archives - DYPALL Network","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dypall.com\/es\/category\/activity\/","og_locale":"es_ES","og_type":"article","og_title":"Activity Archives - DYPALL Network","og_url":"https:\/\/dypall.com\/es\/category\/activity\/","og_site_name":"DYPALL Network","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/dypall.com\/category\/activity\/","url":"https:\/\/dypall.com\/category\/activity\/","name":"Activity Archives - DYPALL Network","isPartOf":{"@id":"https:\/\/dypall.com\/#website"},"breadcrumb":{"@id":"https:\/\/dypall.com\/category\/activity\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/dypall.com\/category\/activity\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dypall.com\/"},{"@type":"ListItem","position":2,"name":"Activity"}]},{"@type":"WebSite","@id":"https:\/\/dypall.com\/#website","url":"https:\/\/dypall.com\/","name":"DYPALL Network","description":"We are a European network of civil society organisations, municipalities and research institutions dedicated to improving democracy through youth participation.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dypall.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/dypall.com\/es\/wp-json\/wp\/v2\/categories\/111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dypall.com\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/dypall.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/dypall.com\/es\/wp-json\/wp\/v2\/posts?categories=111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}